{"id":170,"count":2,"description":"","link":"http:\/\/www.gildedserpent.com\/cms\/category\/asia\/","name":"Asia","slug":"asia","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.gildedserpent.com\/cms\/wp-json\/wp\/v2\/categories\/170"}],"collection":[{"href":"http:\/\/www.gildedserpent.com\/cms\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.gildedserpent.com\/cms\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.gildedserpent.com\/cms\/wp-json\/wp\/v2\/posts?categories=170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}