{"id":31,"count":71,"description":"","link":"http:\/\/www.gildedserpent.com\/cms\/category\/community\/","name":"Community","slug":"community","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.gildedserpent.com\/cms\/wp-json\/wp\/v2\/categories\/31"}],"collection":[{"href":"http:\/\/www.gildedserpent.com\/cms\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.gildedserpent.com\/cms\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.gildedserpent.com\/cms\/wp-json\/wp\/v2\/posts?categories=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}