{"id":33,"count":6,"description":"","link":"http:\/\/www.gildedserpent.com\/cms\/category\/dabke\/","name":"dabke","slug":"dabke","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.gildedserpent.com\/cms\/wp-json\/wp\/v2\/categories\/33"}],"collection":[{"href":"http:\/\/www.gildedserpent.com\/cms\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.gildedserpent.com\/cms\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.gildedserpent.com\/cms\/wp-json\/wp\/v2\/posts?categories=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}